{"id":2920,"date":"2017-11-13T15:12:59","date_gmt":"2017-11-13T14:12:59","guid":{"rendered":"http:\/\/www.enviroscop.fr\/actu\/?p=2920"},"modified":"2017-11-13T15:12:59","modified_gmt":"2017-11-13T14:12:59","slug":"icpe-la-gestion-des-dechets-en-question","status":"publish","type":"post","link":"https:\/\/www.enviroscop.fr\/actu\/2017\/11\/icpe-la-gestion-des-dechets-en-question\/","title":{"rendered":"ICPE : la gestion des d\u00e9chets en question"},"content":{"rendered":"<p>Le Minist\u00e8re de la Transition \u00e9cologique et solidaire m\u00e8ne actuellement une consultation publique relative au projet de d\u00e9cret modifiant la nomenclature des installations class\u00e9es pour la protection de l\u2019environnement .<\/p>\n<p>Pour nos secteurs d&rsquo;\u00e9tude, elle concerne notamment la gestion des d\u00e9chets inertes de carri\u00e8res, vous pouvez lire le <a href=\"http:\/\/www.consultations-publiques.developpement-durable.gouv.fr\/IMG\/pdf\/bpgd-17-206_d_cret_r_vision_nomenclature-f.pdf\">projet ICI.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Minist\u00e8re de la Transition \u00e9cologique et solidaire m\u00e8ne actuellement une consultation publique relative au projet de d\u00e9cret modifiant la nomenclature des installations class\u00e9es pour la protection de l\u2019environnement . Pour nos secteurs d&rsquo;\u00e9tude, elle concerne notamment la gestion des d\u00e9chets inertes de carri\u00e8res, vous pouvez lire le projet ICI.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13,32,35,38],"tags":[],"class_list":["post-2920","post","type-post","status-publish","format-standard","hentry","category-carrieres","category-icpe","category-juridique","category-ministere","item-wrap"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.enviroscop.fr\/actu\/wp-json\/wp\/v2\/posts\/2920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enviroscop.fr\/actu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enviroscop.fr\/actu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enviroscop.fr\/actu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enviroscop.fr\/actu\/wp-json\/wp\/v2\/comments?post=2920"}],"version-history":[{"count":0,"href":"https:\/\/www.enviroscop.fr\/actu\/wp-json\/wp\/v2\/posts\/2920\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.enviroscop.fr\/actu\/wp-json\/wp\/v2\/media?parent=2920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enviroscop.fr\/actu\/wp-json\/wp\/v2\/categories?post=2920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enviroscop.fr\/actu\/wp-json\/wp\/v2\/tags?post=2920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}